{"id":17,"count":3,"description":"","link":"https:\/\/www.teflcoursereview.com\/blog\/tag\/how-to\/","name":"how to","slug":"how-to","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.teflcoursereview.com\/blog\/wp-json\/wp\/v2\/tags\/17"}],"collection":[{"href":"https:\/\/www.teflcoursereview.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.teflcoursereview.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.teflcoursereview.com\/blog\/wp-json\/wp\/v2\/posts?tags=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}